{"id":4268,"date":"2020-08-09T19:18:51","date_gmt":"2020-08-09T17:18:51","guid":{"rendered":"https:\/\/churchofchrist-eglisedechrist.fr\/?post_type=glossary&#038;p=4268"},"modified":"2020-08-09T19:18:54","modified_gmt":"2020-08-09T17:18:54","slug":"paix","status":"publish","type":"glossary","link":"https:\/\/churchofchrist-eglisedechrist.fr\/en\/lexique\/paix\/","title":{"rendered":"Paix"},"content":{"rendered":"<p>Il y a deux sens au mot paix- tout d&rsquo;abord c&rsquo;est l&rsquo;absence de guerre et de d\u00e9sordre dans ce monde, et l&rsquo;autre ce n&rsquo;est pas l&rsquo;absence de guerre, mais plut\u00f4t la paix int\u00e9rieure, celle de l\u2019\u00e2me et de l&rsquo;esprit.m\u00eame si autour de nous le monde se trouve dans un chaos total.<\/p>","protected":false},"excerpt":{"rendered":"<p>Il y a deux sens au mot paix- tout d&rsquo;abord c&rsquo;est l&rsquo;absence de guerre et de d\u00e9sordre dans ce monde, et l&rsquo;autre ce n&rsquo;est pas l&rsquo;absence de guerre, mais plut\u00f4t la paix int\u00e9rieure, celle de l\u2019\u00e2me et de l&rsquo;esprit.m\u00eame si autour de nous le monde se trouve dans un chaos total.<\/p>","protected":false},"author":2,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4268","glossary","type-glossary","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paix - Eglise de Christ<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/churchofchrist-eglisedechrist.fr\/en\/lexique\/paix\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paix - Eglise de Christ\" \/>\n<meta property=\"og:description\" content=\"Il y a deux sens au mot paix- tout d&rsquo;abord c&rsquo;est l&rsquo;absence de guerre et de d\u00e9sordre dans ce monde, et l&rsquo;autre ce n&rsquo;est pas l&rsquo;absence de guerre, mais plut\u00f4t la paix int\u00e9rieure, celle de l\u2019\u00e2me et de l&rsquo;esprit.m\u00eame si autour de nous le monde se trouve dans un chaos total.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/churchofchrist-eglisedechrist.fr\/en\/lexique\/paix\/\" \/>\n<meta property=\"og:site_name\" content=\"Eglise de Christ\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-09T17:18:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/churchofchrist-eglisedechrist.fr\\\/lexique\\\/paix\\\/\",\"url\":\"https:\\\/\\\/churchofchrist-eglisedechrist.fr\\\/lexique\\\/paix\\\/\",\"name\":\"Paix - Eglise de Christ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/churchofchrist-eglisedechrist.fr\\\/#website\"},\"datePublished\":\"2020-08-09T17:18:51+00:00\",\"dateModified\":\"2020-08-09T17:18:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/churchofchrist-eglisedechrist.fr\\\/lexique\\\/paix\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/churchofchrist-eglisedechrist.fr\\\/lexique\\\/paix\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/churchofchrist-eglisedechrist.fr\\\/lexique\\\/paix\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/churchofchrist-eglisedechrist.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/churchofchrist-eglisedechrist.fr\\\/#website\",\"url\":\"https:\\\/\\\/churchofchrist-eglisedechrist.fr\\\/\",\"name\":\"Eglise de Christ\",\"description\":\"Paris, France\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/churchofchrist-eglisedechrist.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paix - Eglise de Christ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/churchofchrist-eglisedechrist.fr\/en\/lexique\/paix\/","og_locale":"en_US","og_type":"article","og_title":"Paix - Eglise de Christ","og_description":"Il y a deux sens au mot paix- tout d&rsquo;abord c&rsquo;est l&rsquo;absence de guerre et de d\u00e9sordre dans ce monde, et l&rsquo;autre ce n&rsquo;est pas l&rsquo;absence de guerre, mais plut\u00f4t la paix int\u00e9rieure, celle de l\u2019\u00e2me et de l&rsquo;esprit.m\u00eame si autour de nous le monde se trouve dans un chaos total.","og_url":"https:\/\/churchofchrist-eglisedechrist.fr\/en\/lexique\/paix\/","og_site_name":"Eglise de Christ","article_modified_time":"2020-08-09T17:18:54+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/churchofchrist-eglisedechrist.fr\/lexique\/paix\/","url":"https:\/\/churchofchrist-eglisedechrist.fr\/lexique\/paix\/","name":"Paix - Eglise de Christ","isPartOf":{"@id":"https:\/\/churchofchrist-eglisedechrist.fr\/#website"},"datePublished":"2020-08-09T17:18:51+00:00","dateModified":"2020-08-09T17:18:54+00:00","breadcrumb":{"@id":"https:\/\/churchofchrist-eglisedechrist.fr\/lexique\/paix\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/churchofchrist-eglisedechrist.fr\/lexique\/paix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/churchofchrist-eglisedechrist.fr\/lexique\/paix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/churchofchrist-eglisedechrist.fr\/"},{"@type":"ListItem","position":2,"name":"Paix"}]},{"@type":"WebSite","@id":"https:\/\/churchofchrist-eglisedechrist.fr\/#website","url":"https:\/\/churchofchrist-eglisedechrist.fr\/","name":"Eglise de Christ","description":"Paris, France","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/churchofchrist-eglisedechrist.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/churchofchrist-eglisedechrist.fr\/en\/wp-json\/wp\/v2\/glossary\/4268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/churchofchrist-eglisedechrist.fr\/en\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/churchofchrist-eglisedechrist.fr\/en\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/churchofchrist-eglisedechrist.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/churchofchrist-eglisedechrist.fr\/en\/wp-json\/wp\/v2\/glossary\/4268\/revisions"}],"predecessor-version":[{"id":4269,"href":"https:\/\/churchofchrist-eglisedechrist.fr\/en\/wp-json\/wp\/v2\/glossary\/4268\/revisions\/4269"}],"wp:attachment":[{"href":"https:\/\/churchofchrist-eglisedechrist.fr\/en\/wp-json\/wp\/v2\/media?parent=4268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}